{"id":1280,"date":"2026-01-21T13:12:38","date_gmt":"2026-01-21T13:12:38","guid":{"rendered":"https:\/\/new.elettromeccanicabonato.it\/faq\/"},"modified":"2026-05-18T13:33:32","modified_gmt":"2026-05-18T13:33:32","slug":"faq","status":"publish","type":"page","link":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#2d2d2d\u00a0\u00bb custom_padding=\u00a0\u00bb8%||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb20%||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb30%||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text module_class=\u00a0\u00bbbonato-title-lines\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbHelvetica Now Display &#8211; Bold||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb6em\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb6em\u00a0\u00bb header_font_size_phone=\u00a0\u00bb4em\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>FAQ<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_accordion open_toggle_text_color=\u00a0\u00bb#D9D9D9&Prime; open_toggle_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb closed_toggle_background_color=\u00a0\u00bbrgba(147,149,152,0.12)\u00a0\u00bb toggle_icon=\u00a0\u00bb&#xe050;||divi||400&Prime; icon_color=\u00a0\u00bb#E2E419&Prime; use_icon_font_size=\u00a0\u00bbon\u00a0\u00bb icon_font_size=\u00a0\u00bb25px\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb toggle_text_color=\u00a0\u00bb#D9D9D9&Prime; toggle_font_size=\u00a0\u00bb25px\u00a0\u00bb body_text_color=\u00a0\u00bb#F7F7F7&Prime; body_font_size=\u00a0\u00bb18px\u00a0\u00bb body_letter_spacing=\u00a0\u00bb0.7px\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; toggle_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb toggle_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb toggle_font_size_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb toggle_line_height_tablet=\u00a0\u00bb\u00a0\u00bb toggle_line_height_phone=\u00a0\u00bb1.2em\u00a0\u00bb toggle_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_radii=\u00a0\u00bbon|0.5rem|0.5rem|0.5rem|0.5rem\u00a0\u00bb border_color_all=\u00a0\u00bb#939598&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][et_pb_accordion_item title=\u00a0\u00bbQu\u2019est-ce que l\u2019\u00e9lectricit\u00e9 statique ?\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Il s&rsquo;agit d&rsquo;une accumulation de charges \u00e9lectriques sur une surface, souvent caus\u00e9e par le frottement entre deux mat\u00e9riaux diff\u00e9rents.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbPourquoi l\u2019\u00e9lectricit\u00e9 statique s\u2019accumule-t-elle ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Elle s&rsquo;accumule lorsque les \u00e9lectrons se transf\u00e8rent d&rsquo;un objet \u00e0 l&rsquo;autre, cr\u00e9ant un d\u00e9s\u00e9quilibre entre les charges positives et n\u00e9gatives.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQuels sont les effets courants de l\u2019\u00e9lectricit\u00e9 statique ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>D\u00e9charges \u00e9lectriques pour les op\u00e9rateurs, attraction de poussi\u00e8re, dommages aux composants \u00e9lectroniques, blocages.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbL\u2019\u00e9lectricit\u00e9 statique est-elle dangereuse ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>G\u00e9n\u00e9ralement non pour l&rsquo;homme (elle peut seulement \u00eatre g\u00eanante), mais elle peut \u00eatre dangereuse dans des environnements inflammables ou pour des \u00e9quipements \u00e9lectroniques sensibles.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbO\u00f9 se manifeste-t-elle le plus fr\u00e9quemment ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb]<\/p>\n<p>Dans des environnements secs, pendant l&rsquo;hiver, ou dans des lieux comportant des mat\u00e9riaux synth\u00e9tiques (par exemple moquette, plastique, etc.).<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbComment fonctionne une barre antistatique ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb]<\/p>\n<p>La barre antistatique est \u00e9quip\u00e9e d&rsquo;\u00e9metteurs haute tension qui ionisent l&rsquo;air ambiant, produisant des ions positifs et n\u00e9gatifs. Lorsqu&rsquo;un objet pr\u00e9sente une charge \u00e9lectrostatique (positive ou n\u00e9gative), il attire les ions de polarit\u00e9 oppos\u00e9e g\u00e9n\u00e9r\u00e9s par la barre.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbO\u00f9 doit-on installer une barre antistatique ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb]<\/p>\n<p>La barre antistatique, ainsi que tous les dispositifs d&rsquo;\u00e9limination des charges \u00e9lectrostatiques, doit \u00eatre install\u00e9e juste avant que le probl\u00e8me ne se manifeste. En effet, si elle est install\u00e9e trop en amont, le mat\u00e9riau aura le temps de se recharger \u00e0 nouveau, rendant ainsi l&rsquo;installation inefficace. <\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbDans quelles applications peut-on \u00e9liminer les charges \u00e9lectrostatiques ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb]<\/p>\n<p>Les charges \u00e9lectrostatiques peuvent se trouver dans de tr\u00e8s nombreux environnements industriels, notamment la production et la transformation du plastique (extrusion, injection, emballages souples, converting), le secteur textile, l&rsquo;industrie de l&rsquo;impression, l&rsquo;assemblage \u00e9lectronique, l&rsquo;\u00e9tiquetage, l&rsquo;industrie du bois.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQuels sont les avantages de l\u2019installation d\u2019une barre antistatique ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bboff\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>\u00c9liminer les charges \u00e9lectrostatiques comporte une s\u00e9rie d&rsquo;avantages, notamment la r\u00e9duction de l&rsquo;attraction de la poussi\u00e8re, la pr\u00e9vention des d\u00e9charges \u00e9lectriques pour les op\u00e9rateurs (augmentant ainsi leur s\u00e9curit\u00e9), l&rsquo;am\u00e9lioration de la qualit\u00e9 du produit final (moins de d\u00e9fauts), l&rsquo;augmentation de la productivit\u00e9 (moins d&rsquo;arr\u00eats machine dus aux blocages caus\u00e9s par les charges statiques).<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbDans quel but devrais-je installer une barre de charge \u00e9lectrostatique ?\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb open=\u00a0\u00bbon\u00a0\u00bb]<\/p>\n<p>Les charges \u00e9lectrostatiques peuvent \u00eatre g\u00e9n\u00e9r\u00e9es de mani\u00e8re contr\u00f4l\u00e9e pour cr\u00e9er une adh\u00e9sion temporaire entre deux mat\u00e9riaux. Il est ainsi possible d&rsquo;\u00e9viter l&rsquo;utilisation de mat\u00e9riaux adh\u00e9sifs (colles, rubans) et d&rsquo;automatiser certains processus. <\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FAQIl s&rsquo;agit d&rsquo;une accumulation de charges \u00e9lectriques sur une surface, souvent caus\u00e9e par le frottement entre deux mat\u00e9riaux diff\u00e9rents.Elle s&rsquo;accumule lorsque les \u00e9lectrons se transf\u00e8rent d&rsquo;un objet \u00e0 l&rsquo;autre, cr\u00e9ant un d\u00e9s\u00e9quilibre entre les charges positives et n\u00e9gatives.D\u00e9charges \u00e9lectriques pour les op\u00e9rateurs, attraction de poussi\u00e8re, dommages aux composants \u00e9lectroniques, blocages.G\u00e9n\u00e9ralement non pour l&rsquo;homme (elle peut [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1281,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1280","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FAQ - Elettromeccanica Bonato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elettromeccanicabonato.it\/fr\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ - Elettromeccanica Bonato\" \/>\n<meta property=\"og:description\" content=\"FAQIl s&#039;agit d&#039;une accumulation de charges \u00e9lectriques sur une surface, souvent caus\u00e9e par le frottement entre deux mat\u00e9riaux diff\u00e9rents.Elle s&#039;accumule lorsque les \u00e9lectrons se transf\u00e8rent d&#039;un objet \u00e0 l&#039;autre, cr\u00e9ant un d\u00e9s\u00e9quilibre entre les charges positives et n\u00e9gatives.D\u00e9charges \u00e9lectriques pour les op\u00e9rateurs, attraction de poussi\u00e8re, dommages aux composants \u00e9lectroniques, blocages.G\u00e9n\u00e9ralement non pour l&#039;homme (elle peut [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elettromeccanicabonato.it\/fr\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Elettromeccanica Bonato\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-18T13:33:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elettromeccanicabonato.it\/wp-content\/uploads\/2026\/01\/125171.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"910\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/faq\\\/\",\"url\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/faq\\\/\",\"name\":\"FAQ - Elettromeccanica Bonato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/faq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/faq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/125171.jpg\",\"datePublished\":\"2026-01-21T13:12:38+00:00\",\"dateModified\":\"2026-05-18T13:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/faq\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/faq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/faq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/125171.jpg\",\"contentUrl\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/125171.jpg\",\"width\":1000,\"height\":910},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/#website\",\"url\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/\",\"name\":\"Elettromeccanica Bonato\",\"description\":\"Electrostatic Control Systems\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elettromeccanicabonato.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAQ - Elettromeccanica Bonato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/","og_locale":"fr_FR","og_type":"article","og_title":"FAQ - Elettromeccanica Bonato","og_description":"FAQIl s'agit d'une accumulation de charges \u00e9lectriques sur une surface, souvent caus\u00e9e par le frottement entre deux mat\u00e9riaux diff\u00e9rents.Elle s'accumule lorsque les \u00e9lectrons se transf\u00e8rent d'un objet \u00e0 l'autre, cr\u00e9ant un d\u00e9s\u00e9quilibre entre les charges positives et n\u00e9gatives.D\u00e9charges \u00e9lectriques pour les op\u00e9rateurs, attraction de poussi\u00e8re, dommages aux composants \u00e9lectroniques, blocages.G\u00e9n\u00e9ralement non pour l'homme (elle peut [&hellip;]","og_url":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/","og_site_name":"Elettromeccanica Bonato","article_modified_time":"2026-05-18T13:33:32+00:00","og_image":[{"width":1000,"height":910,"url":"https:\/\/elettromeccanicabonato.it\/wp-content\/uploads\/2026\/01\/125171.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/","url":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/","name":"FAQ - Elettromeccanica Bonato","isPartOf":{"@id":"https:\/\/elettromeccanicabonato.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/#primaryimage"},"image":{"@id":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/#primaryimage"},"thumbnailUrl":"https:\/\/elettromeccanicabonato.it\/wp-content\/uploads\/2026\/01\/125171.jpg","datePublished":"2026-01-21T13:12:38+00:00","dateModified":"2026-05-18T13:33:32+00:00","breadcrumb":{"@id":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elettromeccanicabonato.it\/fr\/faq\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/#primaryimage","url":"https:\/\/elettromeccanicabonato.it\/wp-content\/uploads\/2026\/01\/125171.jpg","contentUrl":"https:\/\/elettromeccanicabonato.it\/wp-content\/uploads\/2026\/01\/125171.jpg","width":1000,"height":910},{"@type":"BreadcrumbList","@id":"https:\/\/elettromeccanicabonato.it\/fr\/faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elettromeccanicabonato.it\/fr\/"},{"@type":"ListItem","position":2,"name":"FAQ"}]},{"@type":"WebSite","@id":"https:\/\/elettromeccanicabonato.it\/#website","url":"https:\/\/elettromeccanicabonato.it\/","name":"Elettromeccanica Bonato","description":"Electrostatic Control Systems","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elettromeccanicabonato.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/pages\/1280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/comments?post=1280"}],"version-history":[{"count":5,"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/pages\/1280\/revisions"}],"predecessor-version":[{"id":3642,"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/pages\/1280\/revisions\/3642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/media\/1281"}],"wp:attachment":[{"href":"https:\/\/elettromeccanicabonato.it\/fr\/wp-json\/wp\/v2\/media?parent=1280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}